{"id":119,"date":"2024-08-12T19:54:47","date_gmt":"2024-08-12T19:54:47","guid":{"rendered":"https:\/\/mundocalidad.com\/?p=119"},"modified":"2024-08-12T19:59:10","modified_gmt":"2024-08-12T19:59:10","slug":"novaveritas-participa-en-el-primer-encuentro-empresarial-en-ciudad-del-este","status":"publish","type":"post","link":"https:\/\/mundocalidad.com\/index.php\/2024\/08\/12\/novaveritas-participa-en-el-primer-encuentro-empresarial-en-ciudad-del-este\/","title":{"rendered":"Novaveritas Participa en el Primer Encuentro Empresarial en Ciudad del Este"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nos complace anunciar que durante este fin de semana fuimos part\u00edcipes del primer encuentro empresarial en Ciudad del Este, organizado por el Club Conexi\u00f3n &amp; Negocios. Este evento, que cont\u00f3 con el auspicio de la <a href=\"https:\/\/camaradeempresarioscde.org.py\/\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00e1mara de Empresarios de Ciudad del Este &amp; Alto Paran\u00e1,<\/a> reuni\u00f3 a destacadas empresas como Nissei, <a href=\"https:\/\/www.facebook.com\/oxipar\/?locale=es_LA\" target=\"_blank\" rel=\"noreferrer noopener\">Oxipar<\/a>, San Telmo, Banco GNB, entre otras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Novaveritas se hizo presente con una ponencia relacionada con los procesos de certificaci\u00f3n en normas ISO, demostrando nuestro compromiso con la excelencia y el desarrollo empresarial en la regi\u00f3n. Representando a <a href=\"https:\/\/novaveritas.org\/certificaciones\/index.php\/contacto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Novaveritas<\/a>, estuvieron la Lic. Valeria Portillo y el Lic. Mat\u00edas Orue, quienes compartieron sus conocimientos y experiencias en el \u00e1mbito de las certificaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este evento marc\u00f3 un importante hito en la consolidaci\u00f3n de alianzas estrat\u00e9gicas y en la promoci\u00f3n de buenas pr\u00e1cticas en el sector empresarial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"997\" height=\"1024\" src=\"https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.33.48-997x1024.jpeg\" alt=\"\" class=\"wp-image-123\" srcset=\"https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.33.48-997x1024.jpeg 997w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.33.48-292x300.jpeg 292w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.33.48-768x789.jpeg 768w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.33.48.jpeg 1246w\" sizes=\"auto, (max-width: 997px) 100vw, 997px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.30.25-1024x768.jpeg\" alt=\"\" class=\"wp-image-120\" srcset=\"https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.30.25-1024x768.jpeg 1024w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.30.25-300x225.jpeg 300w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.30.25-768x576.jpeg 768w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.30.25-1536x1152.jpeg 1536w, https:\/\/mundocalidad.com\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-08-10-at-18.30.25.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace anunciar que durante este fin de semana fuimos part\u00edcipes del primer encuentro empresarial en Ciudad del<\/p>\n","protected":false},"author":1,"featured_media":121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,9,2],"tags":[42,41,40],"class_list":["post-119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-certificacion","category-empresas","category-normas-iso","tag-ciudad-del-este","tag-emprendimiento","tag-empresas"],"_links":{"self":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/posts\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":3,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/posts\/119\/revisions"}],"predecessor-version":[{"id":125,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/posts\/119\/revisions\/125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/media\/121"}],"wp:attachment":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/media?parent=119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/categories?post=119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/tags?post=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}