{"id":792,"count":16,"description":"","link":"https:\/\/mundocalidad.com\/index.php\/category\/iso-iec-27000-familia\/","name":"ISO IEC 27000 - Familia","slug":"iso-iec-27000-familia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/categories\/792","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mundocalidad.com\/index.php\/wp-json\/wp\/v2\/posts?categories=792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}